{"id":8338,"date":"2024-02-01T15:20:25","date_gmt":"2024-02-01T14:20:25","guid":{"rendered":"https:\/\/teseo.clal.it\/news\/?p=8338"},"modified":"2024-02-01T15:20:27","modified_gmt":"2024-02-01T14:20:27","slug":"il-ruolo-del-mais-nel-panorama-energetico","status":"publish","type":"post","link":"https:\/\/teseo.clal.it\/news\/it\/il-ruolo-del-mais-nel-panorama-energetico\/","title":{"rendered":"Il ruolo del Mais nel panorama energetico"},"content":{"rendered":"\n<p>Di: Elisa Donegatti ed Ester Venturelli<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/teseo.clal.it\/news\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-01-150411.png\" data-rel=\"lightbox-gallery-B40Zr1wL\" data-rl_title=\"Screenshot-2024-02-01-150411\" data-rl_caption=\"\" title=\"Screenshot-2024-02-01-150411\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"420\" src=\"https:\/\/teseo.clal.it\/news\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-01-150411-1024x420.png\" alt=\"\" class=\"wp-image-8339\" style=\"width:819px;height:auto\" srcset=\"https:\/\/teseo.clal.it\/news\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-01-150411-1024x420.png 1024w, https:\/\/teseo.clal.it\/news\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-01-150411-300x123.png 300w, https:\/\/teseo.clal.it\/news\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-01-150411-768x315.png 768w, https:\/\/teseo.clal.it\/news\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-01-150411.png 1525w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/div>\n\n\n<p><strong>L\u2019etanolo viene utilizzato come carburante <\/strong>in combinazione alla benzina in diverse percentuali. In genere, la presenza di etanolo varia tra il 5 e il 10%, ma alcuni carburanti sono composti all\u201985% da etanolo e il restante 15% da benzina.<\/p>\n\n\n\n<p>Nelle ultime settimane<strong> la produzione Statunitense di etanolo \u00e8 diminuita<\/strong> in modo significativo. I fattori determinanti sono la minore redditivit\u00e0 della produzione e il freddo che ha ostacolato la fornitura di gas naturale agli impianti di produzione.&nbsp;<\/p>\n\n\n\n<p>Anche dal lato della <strong>domanda<\/strong> si sono verificati dei rallentamenti: <a href=\"https:\/\/brownfieldagnews.com\/news\/ethanol-supply-jumps-as-production-falls\/\" target=\"_blank\" rel=\"noreferrer noopener\">il freddo ha portato a ridurre i consumi di carburante<\/a>. Allo stesso tempo, anche le esportazioni si sono ridotte. Questo ha permesso agli stock di etanolo di crescere. La maggiore disponibilit\u00e0 sta esercitando una pressione ribassista sui prezzi influenzando negativamente la redditivit\u00e0 della produzione.<\/p>\n\n\n\n<p>Tuttavia, la<strong> redditivit\u00e0 della produzione di etanolo<\/strong> <strong>\u00e8 strettamente legata anche all\u2019andamento delle materie prime<\/strong>, di queste la pi\u00f9 utilizzata negli USA \u00e8 il <strong>Mais<\/strong>. Le <a href=\"https:\/\/teseo.clal.it\/?section=usda_cereali&amp;id_area=world&amp;cod_prod=0440000\" target=\"_blank\" rel=\"noreferrer noopener\">stime USDA <\/a>indicano che la disponibilit\u00e0 di Mais dovrebbe aumentare nel 2024, rispetto al 2023, e questo avrebbe un effetto ribassista sui prezzi del Mais e, di conseguenza, dell\u2019etanolo.<\/p>\n\n\n\n<p><strong>Per quanto sia un carburante economico, non pu\u00f2 essere paragonato alla benzina<\/strong> perch\u00e9 non tutti i motori a benzina possono utilizzarlo ed ha un\u2019efficienza molto inferiore. Negli USA, per\u00f2, si sta investendo nell\u2019utilizzo di etanolo sostenibile come <strong>carburante per l\u2019aviazione<\/strong>, e recentemente \u00e8 stato aperto il primo impianto per la produzione di etanolo sostenibile da utilizzare in aviazione.&nbsp;Lo sviluppo di tale settore garantirebbe <strong>ai produttori di Mais<\/strong> un ruolo di rilevanza nel panorama energetico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Di: Elisa Donegatti ed Ester Venturelli L\u2019etanolo viene utilizzato come carburante in combinazione alla benzina in diverse percentuali. In genere, la presenza di etanolo varia tra il 5 e il 10%, ma alcuni carburanti sono composti all\u201985% da etanolo e il restante 15% da benzina. Nelle ultime settimane la produzione Statunitense di etanolo \u00e8 diminuita &hellip; <a href=\"https:\/\/teseo.clal.it\/news\/it\/il-ruolo-del-mais-nel-panorama-energetico\/\" class=\"more-link\">Continua a leggere <span class=\"screen-reader-text\">Il ruolo del Mais nel panorama energetico<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68,264,7],"tags":[49],"class_list":["post-8338","post","type-post","status-publish","format-standard","hentry","category-energia","category-mais","category-stati-uniti","tag-news-formative"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Il ruolo del Mais nel panorama energetico - TESEO News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/teseo.clal.it\/news\/it\/il-ruolo-del-mais-nel-panorama-energetico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il ruolo del Mais nel panorama energetico - TESEO News\" \/>\n<meta property=\"og:description\" content=\"Di: Elisa Donegatti ed Ester Venturelli L\u2019etanolo viene utilizzato come carburante in combinazione alla benzina in diverse percentuali. In genere, la presenza di etanolo varia tra il 5 e il 10%, ma alcuni carburanti sono composti all\u201985% da etanolo e il restante 15% da benzina. Nelle ultime settimane la produzione Statunitense di etanolo \u00e8 diminuita &hellip; Continua a leggere Il ruolo del Mais nel panorama energetico\" \/>\n<meta property=\"og:url\" content=\"https:\/\/teseo.clal.it\/news\/it\/il-ruolo-del-mais-nel-panorama-energetico\/\" \/>\n<meta property=\"og:site_name\" content=\"TESEO News\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/claldairy\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-01T14:20:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-01T14:20:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/teseo.clal.it\/news\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-01-150411-1024x420.png\" \/>\n<meta name=\"author\" content=\"CLAL Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@claldairy_it\" \/>\n<meta name=\"twitter:site\" content=\"@claldairy_it\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"CLAL Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/teseo.clal.it\/news\/it\/il-ruolo-del-mais-nel-panorama-energetico\/\",\"url\":\"https:\/\/teseo.clal.it\/news\/it\/il-ruolo-del-mais-nel-panorama-energetico\/\",\"name\":\"Il ruolo del Mais nel panorama energetico - TESEO News\",\"isPartOf\":{\"@id\":\"https:\/\/teseo.clal.it\/news\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/teseo.clal.it\/news\/it\/il-ruolo-del-mais-nel-panorama-energetico\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/teseo.clal.it\/news\/it\/il-ruolo-del-mais-nel-panorama-energetico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/teseo.clal.it\/news\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-01-150411-1024x420.png\",\"datePublished\":\"2024-02-01T14:20:25+00:00\",\"dateModified\":\"2024-02-01T14:20:27+00:00\",\"author\":{\"@id\":\"https:\/\/teseo.clal.it\/news\/#\/schema\/person\/2fa0435ad88656a2aed2623d9771d0a6\"},\"breadcrumb\":{\"@id\":\"https:\/\/teseo.clal.it\/news\/it\/il-ruolo-del-mais-nel-panorama-energetico\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/teseo.clal.it\/news\/it\/il-ruolo-del-mais-nel-panorama-energetico\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/teseo.clal.it\/news\/it\/il-ruolo-del-mais-nel-panorama-energetico\/#primaryimage\",\"url\":\"https:\/\/teseo.clal.it\/news\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-01-150411.png\",\"contentUrl\":\"https:\/\/teseo.clal.it\/news\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-01-150411.png\",\"width\":1525,\"height\":625},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/teseo.clal.it\/news\/it\/il-ruolo-del-mais-nel-panorama-energetico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"News\",\"item\":\"https:\/\/teseo.clal.it\/news\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il ruolo del Mais nel panorama energetico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/teseo.clal.it\/news\/#website\",\"url\":\"https:\/\/teseo.clal.it\/news\/\",\"name\":\"TESEO News\",\"description\":\"Le News di TESEO by CLAL.it\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/teseo.clal.it\/news\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/teseo.clal.it\/news\/#\/schema\/person\/2fa0435ad88656a2aed2623d9771d0a6\",\"name\":\"CLAL Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/teseo.clal.it\/news\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/teseo.clal.it\/news\/wp-content\/uploads\/2026\/04\/spiga_132_20260407_facebook-150x150.png\",\"contentUrl\":\"https:\/\/teseo.clal.it\/news\/wp-content\/uploads\/2026\/04\/spiga_132_20260407_facebook-150x150.png\",\"caption\":\"CLAL Team\"},\"description\":\"Il team CLAL.it \u00e8 composto da giovani che, con l'ausilio dell'Informatica, studiano i fenomeni del mercato lattiero-caseario e sviluppano strumenti per offrire agli Operatori del settore una visione complessiva e in tempo reale dell'andamento dei mercati nazionali e internazionali.\",\"url\":\"https:\/\/teseo.clal.it\/news\/author\/clal-team\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il ruolo del Mais nel panorama energetico - TESEO News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/teseo.clal.it\/news\/it\/il-ruolo-del-mais-nel-panorama-energetico\/","og_locale":"it_IT","og_type":"article","og_title":"Il ruolo del Mais nel panorama energetico - TESEO News","og_description":"Di: Elisa Donegatti ed Ester Venturelli L\u2019etanolo viene utilizzato come carburante in combinazione alla benzina in diverse percentuali. In genere, la presenza di etanolo varia tra il 5 e il 10%, ma alcuni carburanti sono composti all\u201985% da etanolo e il restante 15% da benzina. Nelle ultime settimane la produzione Statunitense di etanolo \u00e8 diminuita &hellip; Continua a leggere Il ruolo del Mais nel panorama energetico","og_url":"https:\/\/teseo.clal.it\/news\/it\/il-ruolo-del-mais-nel-panorama-energetico\/","og_site_name":"TESEO News","article_publisher":"https:\/\/www.facebook.com\/claldairy","article_published_time":"2024-02-01T14:20:25+00:00","article_modified_time":"2024-02-01T14:20:27+00:00","og_image":[{"url":"https:\/\/teseo.clal.it\/news\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-01-150411-1024x420.png","type":"","width":"","height":""}],"author":"CLAL Team","twitter_card":"summary_large_image","twitter_creator":"@claldairy_it","twitter_site":"@claldairy_it","twitter_misc":{"Scritto da":"CLAL Team","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/teseo.clal.it\/news\/it\/il-ruolo-del-mais-nel-panorama-energetico\/","url":"https:\/\/teseo.clal.it\/news\/it\/il-ruolo-del-mais-nel-panorama-energetico\/","name":"Il ruolo del Mais nel panorama energetico - TESEO News","isPartOf":{"@id":"https:\/\/teseo.clal.it\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/teseo.clal.it\/news\/it\/il-ruolo-del-mais-nel-panorama-energetico\/#primaryimage"},"image":{"@id":"https:\/\/teseo.clal.it\/news\/it\/il-ruolo-del-mais-nel-panorama-energetico\/#primaryimage"},"thumbnailUrl":"https:\/\/teseo.clal.it\/news\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-01-150411-1024x420.png","datePublished":"2024-02-01T14:20:25+00:00","dateModified":"2024-02-01T14:20:27+00:00","author":{"@id":"https:\/\/teseo.clal.it\/news\/#\/schema\/person\/2fa0435ad88656a2aed2623d9771d0a6"},"breadcrumb":{"@id":"https:\/\/teseo.clal.it\/news\/it\/il-ruolo-del-mais-nel-panorama-energetico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/teseo.clal.it\/news\/it\/il-ruolo-del-mais-nel-panorama-energetico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/teseo.clal.it\/news\/it\/il-ruolo-del-mais-nel-panorama-energetico\/#primaryimage","url":"https:\/\/teseo.clal.it\/news\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-01-150411.png","contentUrl":"https:\/\/teseo.clal.it\/news\/wp-content\/uploads\/2024\/02\/Screenshot-2024-02-01-150411.png","width":1525,"height":625},{"@type":"BreadcrumbList","@id":"https:\/\/teseo.clal.it\/news\/it\/il-ruolo-del-mais-nel-panorama-energetico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"News","item":"https:\/\/teseo.clal.it\/news\/it\/"},{"@type":"ListItem","position":2,"name":"Il ruolo del Mais nel panorama energetico"}]},{"@type":"WebSite","@id":"https:\/\/teseo.clal.it\/news\/#website","url":"https:\/\/teseo.clal.it\/news\/","name":"TESEO News","description":"Le News di TESEO by CLAL.it","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/teseo.clal.it\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/teseo.clal.it\/news\/#\/schema\/person\/2fa0435ad88656a2aed2623d9771d0a6","name":"CLAL Team","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/teseo.clal.it\/news\/#\/schema\/person\/image\/","url":"https:\/\/teseo.clal.it\/news\/wp-content\/uploads\/2026\/04\/spiga_132_20260407_facebook-150x150.png","contentUrl":"https:\/\/teseo.clal.it\/news\/wp-content\/uploads\/2026\/04\/spiga_132_20260407_facebook-150x150.png","caption":"CLAL Team"},"description":"Il team CLAL.it \u00e8 composto da giovani che, con l'ausilio dell'Informatica, studiano i fenomeni del mercato lattiero-caseario e sviluppano strumenti per offrire agli Operatori del settore una visione complessiva e in tempo reale dell'andamento dei mercati nazionali e internazionali.","url":"https:\/\/teseo.clal.it\/news\/author\/clal-team\/"}]}},"_links":{"self":[{"href":"https:\/\/teseo.clal.it\/news\/wp-json\/wp\/v2\/posts\/8338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teseo.clal.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teseo.clal.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teseo.clal.it\/news\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/teseo.clal.it\/news\/wp-json\/wp\/v2\/comments?post=8338"}],"version-history":[{"count":2,"href":"https:\/\/teseo.clal.it\/news\/wp-json\/wp\/v2\/posts\/8338\/revisions"}],"predecessor-version":[{"id":8341,"href":"https:\/\/teseo.clal.it\/news\/wp-json\/wp\/v2\/posts\/8338\/revisions\/8341"}],"wp:attachment":[{"href":"https:\/\/teseo.clal.it\/news\/wp-json\/wp\/v2\/media?parent=8338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teseo.clal.it\/news\/wp-json\/wp\/v2\/categories?post=8338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teseo.clal.it\/news\/wp-json\/wp\/v2\/tags?post=8338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}